{"id":2759,"date":"2022-07-12T21:21:29","date_gmt":"2022-07-12T21:21:29","guid":{"rendered":"https:\/\/proqc.fr\/blog\/?p=2759"},"modified":"2023-11-02T19:18:38","modified_gmt":"2023-11-02T19:18:38","slug":"5-choses-a-savoir-sur-les-inspections-avant-expedition","status":"publish","type":"post","link":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/","title":{"rendered":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition"},"content":{"rendered":"<p class=\"lead text-justify\">Les inspections avant exp\u00e9dition (PSI) font partie int\u00e9grante du processus de gestion de la cha\u00eene d&rsquo;approvisionnement.<\/p>\n<p class=\"text-justify\">Elles permettent de v\u00e9rifier la quantit\u00e9 et la qualit\u00e9 des produits nouvellement fabriqu\u00e9s avant leur exp\u00e9dition de l&rsquo;usine. Alors, quelles sont les cinq principales choses que vous devez savoir sur cet important processus de contr\u00f4le de la qualit\u00e9 ?<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg\" class=\"img-fluid\" alt=\"inspections avant exp\u00e9dition\"><\/p>\n<h2 class=\"mt-5\">L&rsquo;inspection avant exp\u00e9dition est une inspection al\u00e9atoire syst\u00e9matique<\/h2>\n<p class=\"text-justify\">L&rsquo;inspection avant exp\u00e9dition est une inspection syst\u00e9matique des unit\u00e9s fabriqu\u00e9es qui sont choisies au hasard parmi tous les lots pr\u00e9par\u00e9s pour l&rsquo;exp\u00e9dition. Cette inspection est effectu\u00e9e lorsque la production est termin\u00e9e \u00e0 100 % et emball\u00e9e \u00e0 80 % &#8211; le tout selon les normes de niveau de qualit\u00e9 acceptable (NQA), ou en fonction des exigences sp\u00e9cifiques du client.<\/p>\n<p class=\"text-justify\">L&rsquo;\u00e9chantillonnage al\u00e9atoire permet \u00e0 l&rsquo;\u00e9quipe de contr\u00f4le de la qualit\u00e9 d&rsquo;estimer efficacement le niveau de qualit\u00e9 du lot complet de produits fabriqu\u00e9s. Pour en savoir plus sur la fa\u00e7on dont l&rsquo;\u00e9chantillonnage est effectu\u00e9, consultez l&rsquo;article : <a href=\"https:\/\/proqc.com\/blog\/5-things-you-probably-didnt-know-about-aql\/\">https:\/\/proqc.com\/blog\/5-things-you-probably-didnt-know-about-aql\/<\/a>.<\/p>\n<h2 class=\"mt-5\">Les inspections avant exp\u00e9dition permettent d&rsquo;\u00e9viter les retards et les r\u00e9usinages co\u00fbteux<\/h2>\n<p class=\"text-justify\">Moyen plus rapide et moins co\u00fbteux d&rsquo;avoir un aper\u00e7u d&rsquo;une commande plus importante, l&rsquo;inspection avant exp\u00e9dition permet \u00e0 l&rsquo;\u00e9quipe de v\u00e9rifier la qualit\u00e9 et la quantit\u00e9 des produits fabriqu\u00e9s, de contr\u00f4ler les \u00e9ventuels d\u00e9fauts des produits et de s&rsquo;assurer que les produits et les emballages r\u00e9pondent aux normes de s\u00e9curit\u00e9 requises pour le march\u00e9 de destination. Cela permet de corriger efficacement les \u00e9ventuels d\u00e9fauts des produits avant l&rsquo;exp\u00e9dition.<\/p>\n<p class=\"text-justify\">Ici, \u00e0 Pro QC, nous avons vu plusieurs cas o\u00f9 les importateurs n&rsquo;ont pas inspect\u00e9 les produits avant l&rsquo;exp\u00e9dition, et apr\u00e8s les avoir re\u00e7us dans leurs propres entrep\u00f4ts, ils n&rsquo;ont pas pu les vendre sur le march\u00e9. Cela a augment\u00e9 leurs co\u00fbts de reconditionnement, avec des retards (et des d\u00e9penses suppl\u00e9mentaires) caus\u00e9s par l&rsquo;obligation de renvoyer les produits \u00e0 l&rsquo;usine ou d&rsquo;\u00e9liminer des cargaisons enti\u00e8res.<\/p>\n<h2 class=\"mt-5\">Les services d&rsquo;inspection avant exp\u00e9dition am\u00e9liorent l&rsquo;efficacit\u00e9 des importations<\/h2>\n<p class=\"text-justify\">Afin d&rsquo;\u00e9viter tout probl\u00e8me r\u00e9glementaire, les services d&rsquo;inspection avant exp\u00e9dition permettent de s&rsquo;assurer que les certificats et rapports d&rsquo;inspection sont en ordre pour l&rsquo;exp\u00e9dition sortante. Il incombe aux importateurs de s&rsquo;assurer que ces exigences l\u00e9gales sont respect\u00e9es. Les certifications facilitent donc le processus de d\u00e9douanement, qui peut autrement prendre beaucoup plus de temps.<\/p>\n<p class=\"text-justify\">Une inspection avant exp\u00e9dition permet de v\u00e9rifier que les produits sont conformes aux normes et r\u00e9glementations de s\u00e9curit\u00e9, prouvant qu&rsquo;ils ne pr\u00e9sentent pas de danger pour la sant\u00e9, la s\u00e9curit\u00e9 ou l&rsquo;environnement. Tous les produits et emballages doivent \u00e9galement \u00eatre v\u00e9rifi\u00e9s pour s&rsquo;assurer qu&rsquo;ils portent les marques de certification requises (par exemple, la marque CE pour le march\u00e9 de l&rsquo;UE).<\/p>\n<p class=\"text-justify\">Si un produit ne r\u00e9pond pas aux exigences du march\u00e9, il sera soumis \u00e0 des restrictions \u00e0 l&rsquo;importation &#8211; y compris le blocage par les douanes, ou fera l&rsquo;objet d&rsquo;un rappel ou d&rsquo;une destruction.<\/p>\n<h2 class=\"mt-5\">L&rsquo;inspection avant exp\u00e9dition est un outil efficace pour prot\u00e9ger la r\u00e9putation d&rsquo;une marque<\/h2>\n<p class=\"text-justify\">Une inspection avant exp\u00e9dition <strong>prot\u00e8ge la r\u00e9putation des entreprises<\/strong>. Gr\u00e2ce au PSI, elles livreront des produits de haute qualit\u00e9 \u00e0 leurs clients et prot\u00e9geront leur r\u00e9putation et leur image de marque.<\/p>\n<p class=\"text-justify\">Une mauvaise qualit\u00e9 de produit peut \u00eatre destructrice pour la r\u00e9putation d&rsquo;une marque, entra\u00eenant des co\u00fbts financiers et op\u00e9rationnels importants. Les rappels de produits peuvent nuire au sentiment des consommateurs, les amenant \u00e0 se m\u00e9fier de la marque dans des sc\u00e9narios futurs, tout en \u00e9tant \u00e9galement co\u00fbteux.<\/p>\n<h2 class=\"mt-5\">L&rsquo;inspection avant exp\u00e9dition peut am\u00e9liorer les normes du commerce international<\/h2>\n<p class=\"text-justify\">Les inspections avant exp\u00e9dition ont \u00e9t\u00e9 officiellement introduites comme un accord visant \u00e0 am\u00e9liorer les normes du commerce international dans le cadre de <strong>l&rsquo;Organisation mondiale du commerce (OMC)<\/strong>.<\/p>\n<p class=\"text-justify\">L&rsquo;accord de l&rsquo;OMC visait \u00e0 am\u00e9liorer le processus d&rsquo;IAE en \u00e9tablissant des proc\u00e9dures et des calendriers \u00e9quitables et compr\u00e9hensibles, tout en rendant les gouvernements des pays importateurs responsables des actions des soci\u00e9t\u00e9s d&rsquo;inspection avant exp\u00e9dition qu&rsquo;ils utilisent.<\/p>\n<p class=\"text-justify\">Pro QC est une soci\u00e9t\u00e9 d&rsquo;inspection tierce partie de confiance mondiale offrant des services dans plus de 88 pays suppl\u00e9mentaires. Visitez la page <a href=\"https:\/\/proqc.fr\/inspections-de-produits\/\">https:\/\/proqc.fr\/inspections-de-produits\/<\/a> pour en savoir plus sur nos solutions d&rsquo;inspection.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les inspections avant exp\u00e9dition (PSI) font partie int\u00e9grante du processus de gestion de la cha\u00eene d&rsquo;approvisionnement. Elles permettent [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260],"tags":[319],"class_list":["post-2759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspections-de-produits","tag-inspections-avant-expedition"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)<\/title>\n<meta name=\"description\" content=\"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d&#039;\u00eatre exp\u00e9di\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)\" \/>\n<meta property=\"og:description\" content=\"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d&#039;\u00eatre exp\u00e9di\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Pro QC\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-12T21:21:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T19:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"deborah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"deborah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/\"},\"author\":{\"name\":\"deborah\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\"},\"headline\":\"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition\",\"datePublished\":\"2022-07-12T21:21:29+00:00\",\"dateModified\":\"2023-11-02T19:18:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/\"},\"wordCount\":800,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/pre-shipment-inspection-psi-2048x1365-1.jpeg\",\"keywords\":[\"inspections avant exp\u00e9dition\"],\"articleSection\":[\"inspections de produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/\",\"name\":\"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/pre-shipment-inspection-psi-2048x1365-1.jpeg\",\"datePublished\":\"2022-07-12T21:21:29+00:00\",\"dateModified\":\"2023-11-02T19:18:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\"},\"description\":\"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d'\u00eatre exp\u00e9di\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/pre-shipment-inspection-psi-2048x1365-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/pre-shipment-inspection-psi-2048x1365-1.jpeg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/5-choses-a-savoir-sur-les-inspections-avant-expedition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/\",\"name\":\"Blog de Pro QC\",\"description\":\"Informez-vous sur les derni\u00e8res nouvelles et les \u00e9volutions du monde du contr\u00f4le qualit\u00e9 gr\u00e2ce au blog de Pro QC International.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\",\"name\":\"deborah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"caption\":\"deborah\"},\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/author\\\/deborah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)","description":"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d'\u00eatre exp\u00e9di\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/","og_locale":"fr_FR","og_type":"article","og_title":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)","og_description":"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d'\u00eatre exp\u00e9di\u00e9s.","og_url":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/","og_site_name":"Blog de Pro QC","article_published_time":"2022-07-12T21:21:29+00:00","article_modified_time":"2023-11-02T19:18:38+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg","type":"image\/jpeg"}],"author":"deborah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"deborah","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#article","isPartOf":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/"},"author":{"name":"deborah","@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65"},"headline":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition","datePublished":"2022-07-12T21:21:29+00:00","dateModified":"2023-11-02T19:18:38+00:00","mainEntityOfPage":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/"},"wordCount":800,"commentCount":0,"image":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#primaryimage"},"thumbnailUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg","keywords":["inspections avant exp\u00e9dition"],"articleSection":["inspections de produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/","url":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/","name":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition (IAE)","isPartOf":{"@id":"https:\/\/proqc.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#primaryimage"},"image":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#primaryimage"},"thumbnailUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg","datePublished":"2022-07-12T21:21:29+00:00","dateModified":"2023-11-02T19:18:38+00:00","author":{"@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65"},"description":"5 choses que vous devez savoir sur les inspections avant exp\u00e9dition qui garantissent que les produits sont contr\u00f4l\u00e9s avant d'\u00eatre exp\u00e9di\u00e9s.","breadcrumb":{"@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#primaryimage","url":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg","contentUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/07\/pre-shipment-inspection-psi-2048x1365-1.jpeg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/proqc.fr\/blog\/5-choses-a-savoir-sur-les-inspections-avant-expedition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proqc.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"5 choses \u00e0 savoir sur les inspections avant exp\u00e9dition"}]},{"@type":"WebSite","@id":"https:\/\/proqc.fr\/blog\/#website","url":"https:\/\/proqc.fr\/blog\/","name":"Blog de Pro QC","description":"Informez-vous sur les derni\u00e8res nouvelles et les \u00e9volutions du monde du contr\u00f4le qualit\u00e9 gr\u00e2ce au blog de Pro QC International.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proqc.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65","name":"deborah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","caption":"deborah"},"url":"https:\/\/proqc.fr\/blog\/author\/deborah\/"}]}},"_links":{"self":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/comments?post=2759"}],"version-history":[{"count":2,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2759\/revisions"}],"predecessor-version":[{"id":2762,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2759\/revisions\/2762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/media\/2758"}],"wp:attachment":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/media?parent=2759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/categories?post=2759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/tags?post=2759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}