{"id":2601,"date":"2022-02-11T10:23:57","date_gmt":"2022-02-11T10:23:57","guid":{"rendered":"https:\/\/proqc.fr\/blog\/?p=2601"},"modified":"2023-11-02T20:43:48","modified_gmt":"2023-11-02T20:43:48","slug":"comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit","status":"publish","type":"post","link":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/","title":{"rendered":"Comprendre les audits de dispositifs m\u00e9dicaux et leurs rapports d&rsquo;audit"},"content":{"rendered":"<p><em>Pro QC International accompagne facilement ses clients et partage leur succ\u00e8s<\/em><\/p>\n<p>Le <a href=\"https:\/\/proqc.fr\/industries\/controle-qualite-dispositifs-medicaux\/\">secteur des dispositifs m\u00e9dicaux<\/a> doit produire des produits s\u00fbrs et efficaces pour diagnostiquer et traiter les maladies. Chaque ann\u00e9e, les exigences de cette industrie deviennent plus strictes, car les organismes de r\u00e9glementation, les organismes de normalisation et les patients attendent davantage en mati\u00e8re de s\u00e9curit\u00e9 et d&rsquo;efficacit\u00e9.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\" alt=\"Audit des fabricants de dispositifs m\u00e9dicaux\"><\/p>\n<p>Pour aider les fabricants de dispositifs m\u00e9dicaux \u00e0 r\u00e9pondre \u00e0 ces besoins toujours croissants, Pro QC International sert de soci\u00e9t\u00e9 d&rsquo;audit tierce partie et fournit un ensemble d&rsquo;audits de fournisseurs et d&rsquo;usines en fonction de chacune des r\u00e9glementations et normes les plus importantes. L&rsquo;article suivant vous expliquera les diff\u00e9rents audits de fabricants de dispositifs m\u00e9dicaux, les normes et r\u00e8glements applicables, et ce \u00e0 quoi vous pouvez vous attendre de nos rapports d&rsquo;audits.<\/p>\n<h2>Types d&rsquo;audit de fabricant de dispositifs m\u00e9dicaux<\/h2>\n<h3>Audit r\u00e9glementaire<\/h3>\n<p>Un fabricant de dispositifs m\u00e9dicaux doit se conformer aux lois du pays dans lequel il exerce et dans lequel il commercialise et vend ses produits. Comme les dispositifs m\u00e9dicaux sont souvent invasifs dans le corps (comme un cath\u00e9ter de contact sanguin) et qu&rsquo;ils influencent les d\u00e9cisions de traitement (comme un dispositif de contr\u00f4le de la glyc\u00e9mie par piq\u00fbre au doigt), ils sont soumis \u00e0 des r\u00e9glementations strictes r\u00e9gissant leur d\u00e9veloppement, leurs tests et leur commercialisation.<\/p>\n<p>Un r\u00e8glement est une norme qui a force de loi derri\u00e8re elle. Cela signifie qu&rsquo;une entreprise qui ne respecte pas un r\u00e8glement peut s&rsquo;attendre \u00e0 des sanctions juridiques et financi\u00e8res, y compris des peines de prison (dans les cas les plus flagrants), des interdictions d&rsquo;importation et la r\u00e9vocation de la licence d&rsquo;exploitation et de vente.<\/p>\n<p>Aux \u00c9tats-Unis, la Food and Drug Administration (FDA) applique les lois relatives aux dispositifs m\u00e9dicaux. La mission de la FDA est de prot\u00e9ger la sant\u00e9 publique. En Europe, un cadre r\u00e9glementaire comprenant des pays ind\u00e9pendants et l&rsquo;Union europ\u00e9enne fait respecter les lois sur les dispositifs m\u00e9dicaux. Dans de nombreux petits pays ou pays en d\u00e9veloppement, le gouvernement local exigera la conformit\u00e9 aux normes internationales ou \u00e0 un processus d\u00e9velopp\u00e9 par l&rsquo;Organisation mondiale de la sant\u00e9 (plus d&rsquo;informations sur les normes ci-dessous) au lieu de d\u00e9velopper leur propre ensemble de r\u00e9glementations complexes.<\/p>\n<p>Un audit r\u00e9glementaire a l&rsquo;un des trois objectifs suivants : la surveillance de routine des op\u00e9rations du fabricant de dispositifs ; l&rsquo;\u00e9valuation des op\u00e9rations du fabricant de dispositifs avant d&rsquo;accorder l&rsquo;autorisation de mise sur le march\u00e9 ; et les inspections pour cause parce que l&rsquo;organisme de r\u00e9glementation a ressenti le besoin d&rsquo;enqu\u00eater sur une \u00e9ventuelle violation.<\/p>\n<p>Un audit r\u00e9glementaire est extr\u00eamement important en raison des cons\u00e9quences potentielles qu&rsquo;il implique.<\/p>\n<h3>Audit de tierce partie<\/h3>\n<p>Un audit tierce partie est un audit r\u00e9alis\u00e9 par un organisme externe \u00e0 la relation client-fournisseur, et donc ind\u00e9pendant. Cet audit peut aider le client \u00e0 obtenir une certification, un agr\u00e9ment ou une reconnaissance.<\/p>\n<p>Le principal atout d&rsquo;un audit par un tiers est l&rsquo;ind\u00e9pendance de l&rsquo;auditeur. Cet aspect de la relation lui permet de faire preuve d&rsquo;objectivit\u00e9 et de d\u00e9tachement lors de la r\u00e9daction des conclusions, et de s&rsquo;en tenir plus \u00e9troitement \u00e0 la norme qu&rsquo;aux particularit\u00e9s de la culture et des coutumes du client ou du fournisseur.<\/p>\n<p>Dans le cadre d&rsquo;un audit ISO 13485, une entreprise ind\u00e9pendante (et non l&rsquo;organisme de normalisation ISO lui-m\u00eame) se rendra sur le site du client, examinera les dossiers et les processus, fera une visite, interrogera le personnel et la direction, et fournira un rapport d&rsquo;audit \u00e9valuant la conformit\u00e9 \u00e0 la norme de syst\u00e8me de gestion de la qualit\u00e9 des dispositifs m\u00e9dicaux. L&rsquo;entit\u00e9 audit\u00e9e aura g\u00e9n\u00e9ralement le temps de r\u00e9pondre aux conclusions avant l&rsquo;audit de suivi. Au cours de l&rsquo;audit de suivi, on v\u00e9rifie \u00e0 nouveau s&rsquo;ils ont corrig\u00e9 les non-conformit\u00e9s \u00e0 la norme. Ensuite, un audit r\u00e9ussi se traduira par un certificat ISO, avec toute la promesse et l&rsquo;int\u00e9grit\u00e9 de l&rsquo;auditeur tiers derri\u00e8re lui.<\/p>\n<h3>Audit du fournisseur<\/h3>\n<p>Un audit de fournisseur est la fa\u00e7on dont une entreprise cliente \u00e9value la qualit\u00e9 et l&rsquo;efficacit\u00e9 de son fournisseur. Par exemple, supposons qu&rsquo;un fabricant de dispositifs fabrique un test de grossesse \u00e0 flux lat\u00e9ral. Ce dispositif est une bandelette apparemment simple o\u00f9 une ligne appara\u00eet pour indiquer une grossesse. Ce fabricant de dispositifs voudra examiner de pr\u00e8s le syst\u00e8me de qualit\u00e9 des fournisseurs de l&rsquo;antig\u00e8ne, du tampon d&rsquo;\u00e9chantillonnage, du tampon \u00e0 m\u00e8che et de la membrane de nitrocellulose.<\/p>\n<p>Un fabricant de dispositifs classera g\u00e9n\u00e9ralement ses fournisseurs en fonction du risque. En fait, cette approche bas\u00e9e sur le risque est une exigence de la norme ISO 13485. Les fournisseurs qui fournissent les composants \u00e0 plus haut risque (comme l&rsquo;antig\u00e8ne) devront faire l&rsquo;objet d&rsquo;un examen plus approfondi que les fournisseurs de l&#8217;emballage ou du bo\u00eetier.<\/p>\n<h2>Que faut-il auditer ?<\/h2>\n<p>\u00ab\u00a0Audit\u00a0\u00bb est g\u00e9n\u00e9ralement synonyme d'\u00a0\u00bbinspection\u00a0\u00bb. L&rsquo;inspection consiste \u00e0 comparer la condition r\u00e9elle \u00e0 l&rsquo;id\u00e9al (c&rsquo;est-\u00e0-dire \u00e0 la norme).<br \/>\n\u00c0 quoi exactement un auditeur compare-t-il un fabricant de dispositifs m\u00e9dicaux lors de l&rsquo;audit de son syst\u00e8me qualit\u00e9 et de ses op\u00e9rations ? La r\u00e9ponse est g\u00e9n\u00e9ralement les r\u00e8glements, les normes et les exigences internes et des fournisseurs.<\/p>\n<h3>R\u00e9glementations<\/h3>\n<p>Auditer en fonction des r\u00e9glementations signifie comparer les op\u00e9rations \u00e0 la loi du pays. Le Code am\u00e9ricain des r\u00e9glementations f\u00e9d\u00e9rales (en particulier 21 CFR Part 820) traite de la mani\u00e8re dont les fabricants de dispositifs m\u00e9dicaux doivent \u00e9tablir un syst\u00e8me qualit\u00e9, c&rsquo;est-\u00e0-dire un ensemble de politiques et de proc\u00e9dures qui garantissent que l&rsquo;entreprise produit des dispositifs s\u00fbrs et efficaces.<\/p>\n<p>Un fabricant de dispositifs m\u00e9dicaux qui commercialise des produits dans l&rsquo;UE devra respecter les r\u00e9glementations du cadre r\u00e9glementaire europ\u00e9en, en particulier le r\u00e8glement relatif aux dispositifs m\u00e9dicaux (MDR), qui est en pleine \u00e9volution. Un fabricant de dispositifs commercialisant des produits en Australie, au Japon, au Canada, etc. devra respecter les r\u00e9glementations de ces pays et souhaitera un audit approfondi par rapport \u00e0 ces r\u00e9glementations avant de demander une autorisation pour le faire.<\/p>\n<h3>Normes<\/h3>\n<p>Que se passe-t-il si la tension art\u00e9rielle d&rsquo;un patient est mesur\u00e9e \u00e9lev\u00e9e sur l&rsquo;appareil de la soci\u00e9t\u00e9 A, et est normale sur l&rsquo;appareil de la soci\u00e9t\u00e9 B ? Cela poserait un probl\u00e8me ! Un organisme de normalisation \u00e9labore des sp\u00e9cifications techniques, des meilleures pratiques et des cadres convenus pour aider les entreprises du monde entier \u00e0 parler le m\u00eame langage technique et \u00e0 atteindre l&rsquo;uniformit\u00e9 dans des domaines importants.<\/p>\n<p>L&rsquo;organisme de normalisation international le plus largement adopt\u00e9 est l&rsquo;Organisation internationale de normalisation (ISO). Leur norme sur le syst\u00e8me de management de la qualit\u00e9 pour les fabricants de dispositifs m\u00e9dicaux, ISO 13485:2016, est utilis\u00e9e par les fabricants du monde entier.<\/p>\n<h3>Exigences internes\/fournisseurs<\/h3>\n<p>Un fabricant de mat\u00e9riel m\u00e9dical classera g\u00e9n\u00e9ralement les fournisseurs en fonction du degr\u00e9 de risque, de critique \u00e0 faible. Les fournisseurs critiques justifient un audit, une inspection, une v\u00e9rification et une vigilance exhaustifs. Le client visitera souvent l&rsquo;usine du fournisseur, examinera ses dossiers, exigera des certifications de tierces parties et un dossier d&rsquo;application r\u00e9glementaire sans faille. Le client d\u00e9veloppera des exigences \u00e9crites et des accords de fournisseur, et auditera le fournisseur par rapport \u00e0 ceux-ci.<\/p>\n<h2>Principaux exemples d&rsquo;audit : Audit ISO 13485 et audit GMP 21 QSR 820<\/h2>\n<h3>Audit ISO 13485<\/h3>\n<p>La norme ISO 13485:2016, selon le <a href=\"https:\/\/www.iso.org\/standard\/59752.html\">site de l&rsquo;ISO<\/a>, \u00ab\u00a0sp\u00e9cifie les exigences relatives \u00e0 un syst\u00e8me de management de la qualit\u00e9 lorsqu&rsquo;un organisme doit d\u00e9montrer son aptitude \u00e0 fournir des dispositifs m\u00e9dicaux et des services connexes qui r\u00e9pondent syst\u00e9matiquement aux exigences des clients et aux exigences r\u00e9glementaires applicables.\u00a0\u00bb<\/p>\n<p>La compr\u00e9hension et la mise en \u0153uvre minutieuse des exigences de cette norme aideront un fabricant de dispositifs m\u00e9dicaux \u00e0 produire syst\u00e9matiquement des produits s\u00fbrs et efficaces tout en r\u00e9alisant une am\u00e9lioration continue.<\/p>\n<p>Compte tenu de son vaste champ d&rsquo;application, la norme ISO 13485 est particuli\u00e8rement concise. Toutefois, satisfaire \u00e0 la norme (un processus appel\u00e9 enregistrement) n&rsquo;est pas simple. Pour y parvenir, la plupart des fabricants de dispositifs m\u00e9dicaux feront appel \u00e0 un service d&rsquo;audit tiers et \u00e9ventuellement \u00e0 un ou deux audits de suivi pour garantir une conformit\u00e9 totale avant d&rsquo;entamer le processus de certification.<\/p>\n<h3>Audit GMP 21 CFR 820<\/h3>\n<p>La FDA am\u00e9ricaine applique les bonnes pratiques de fabrication (BPF) \u00e9nonc\u00e9es dans le Code of Federal Regulations (CFR). Le titre 21, partie 820 d\u00e9crit le r\u00e8glement sur les syst\u00e8mes de qualit\u00e9. Cela peut sembler obscur et compliqu\u00e9, mais le langage et l&rsquo;intention r\u00e9els sont simples : \u00e9tablir dans la loi un cadre qui garantit que les fabricants de dispositifs produisent constamment des produits s\u00fbrs et efficaces.<\/p>\n<h2>Les offres de Pro QC<\/h2>\n<p>En tant que prestataire d&rsquo;audits m\u00e9dicaux, Pro QC propose une gamme d&rsquo;<a href=\"https:\/\/proqc.fr\/industries\/controle-qualite-dispositifs-medicaux\/\">audits qualit\u00e9 fournisseurs<\/a> :<\/p>\n<ul>\n<li>Nouvelle \u00e9valuation des fournisseurs et audit qualit\u00e9<\/li>\n<li>V\u00e9rification des fournisseurs de PPE<\/li>\n<li>Audit du syst\u00e8me de gestion de la qualit\u00e9 ISO 13485 pour les dispositifs m\u00e9dicaux<\/li>\n<li>ISO 11137 Audit du processus de st\u00e9rilisation<\/li>\n<li>Audits GMP 21 QSR 820 pour les dispositifs m\u00e9dicaux<\/li>\n<li>Audits du syst\u00e8me qualit\u00e9 ISO 9001<\/li>\n<li>Audits du syst\u00e8me de gestion environnementale ISO 14001<\/li>\n<li>Inclut la norme ISO 14644<\/li>\n<li>Audits de responsabilit\u00e9 sociale d&rsquo;entreprise<\/li>\n<li>Audits combin\u00e9s<\/li>\n<\/ul>\n<p>Tous sont r\u00e9alis\u00e9s dans le but d&rsquo;aider le client \u00e0 r\u00e9pondre aux exigences r\u00e9glementaires, aux normes et aux besoins de la cha\u00eene d&rsquo;approvisionnement d\u00e9crits plus haut.<\/p>\n<h3>Ce \u00e0 quoi il faut s&rsquo;attendre pendant l&rsquo;audit<\/h3>\n<p>Selon l&rsquo;audit, vous pouvez vous attendre \u00e0 : une inspection et une observation en personne des op\u00e9rations ; un examen des registres et des documents du syst\u00e8me de qualit\u00e9 ; des entretiens avec le personnel ; et une r\u00e9union d&rsquo;ouverture et de cl\u00f4ture pour discuter de la port\u00e9e de l&rsquo;audit et de toute constatation pr\u00e9liminaire. Un audit social n&rsquo;impliquera pas les documents du syst\u00e8me qualit\u00e9, mais un audit ISO 13485 impliquera un examen approfondi de ces documents.<\/p>\n<h3>Ce que vous devez attendre du rapport d&rsquo;audit<\/h3>\n<p>Attendez-vous \u00e0 une liste de recommandations class\u00e9es par ordre de priorit\u00e9, \u00e0 une description claire des points forts et des possibilit\u00e9s d&rsquo;am\u00e9lioration, et \u00e0 une ventilation d\u00e9taill\u00e9e des conclusions. Les constatations sont organis\u00e9es en fonction de l&rsquo;exigence applicable. Chaque constatation est cod\u00e9e par couleur et not\u00e9e, et est li\u00e9e \u00e0 des preuves objectives examin\u00e9es au cours de l&rsquo;audit.<\/p>\n<p>Le rapport de Pro QC comprendra le niveau de risque du fournisseur, le niveau de conformit\u00e9 \u00e0 la norme et les recommandations.<\/p>\n<h3>Consulter des exemples de rapports<\/h3>\n<p>En savoir plus sur les audits de syst\u00e8me qualit\u00e9 et de conformit\u00e9 de Pro QC <a href=\"https:\/\/proqc.com\/services\/factory-supplier-audits\/\">ici<\/a>. Cliquez <a href=\"https:\/\/proqc.fr\/solutions\/exemples-rapports\/\">ici<\/a> pour consulter des exemples de rapports d&rsquo;audit et voir des rapports de premier plan sur la conformit\u00e9 aux r\u00e9glementations, le respect des normes, le d\u00e9veloppement des fournisseurs et la conformit\u00e9 des fournisseurs<\/p>\n<h2>Audits de fabricants de dispositifs m\u00e9dicaux par Pro QC<\/h2>\n<p>Le monde des normes et r\u00e9glementations relatives aux dispositifs m\u00e9dicaux peut sembler d\u00e9courageant, mais il n&rsquo;a pas \u00e0 l&rsquo;\u00eatre. Pro QC s&rsquo;associe \u00e0 ses clients pour r\u00e9aliser des audits et des rapports efficaces. Les clients du secteur des dispositifs m\u00e9dicaux trouveront un partenaire exp\u00e9riment\u00e9 pr\u00eat \u00e0 partager le succ\u00e8s et \u00e0 conduire \u00e0 une am\u00e9lioration majeure de leurs syst\u00e8mes de qualit\u00e9 et de leur production.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pro QC International accompagne facilement ses clients et partage leur succ\u00e8s Le secteur des dispositifs m\u00e9dicaux doit produire [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[247],"tags":[297],"class_list":["post-2601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audit","tag-dispositifs-medicaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485<\/title>\n<meta name=\"description\" content=\"L&#039;article explique les types d&#039;audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d&#039;audit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485\" \/>\n<meta property=\"og:description\" content=\"L&#039;article explique les types d&#039;audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d&#039;audit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Pro QC\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-11T10:23:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T20:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"deborah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"deborah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/\"},\"author\":{\"name\":\"deborah\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\"},\"headline\":\"Comprendre les audits de dispositifs m\u00e9dicaux et leurs rapports d&rsquo;audit\",\"datePublished\":\"2022-02-11T10:23:57+00:00\",\"dateModified\":\"2023-11-02T20:43:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/\"},\"wordCount\":2017,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\",\"keywords\":[\"dispositifs m\u00e9dicaux\"],\"articleSection\":[\"audit\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/\",\"name\":\"Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\",\"datePublished\":\"2022-02-11T10:23:57+00:00\",\"dateModified\":\"2023-11-02T20:43:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\"},\"description\":\"L'article explique les types d'audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d'audit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprendre les audits de dispositifs m\u00e9dicaux et leurs rapports d&rsquo;audit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/\",\"name\":\"Blog de Pro QC\",\"description\":\"Informez-vous sur les derni\u00e8res nouvelles et les \u00e9volutions du monde du contr\u00f4le qualit\u00e9 gr\u00e2ce au blog de Pro QC International.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f103c8700f64ca2a7c8bb9fe24879a65\",\"name\":\"deborah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g\",\"caption\":\"deborah\"},\"url\":\"https:\\\/\\\/proqc.fr\\\/blog\\\/author\\\/deborah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485","description":"L'article explique les types d'audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d'audit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/","og_locale":"fr_FR","og_type":"article","og_title":"Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485","og_description":"L'article explique les types d'audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d'audit.","og_url":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/","og_site_name":"Blog de Pro QC","article_published_time":"2022-02-11T10:23:57+00:00","article_modified_time":"2023-11-02T20:43:48+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg","type":"image\/jpeg"}],"author":"deborah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"deborah","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#article","isPartOf":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/"},"author":{"name":"deborah","@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65"},"headline":"Comprendre les audits de dispositifs m\u00e9dicaux et leurs rapports d&rsquo;audit","datePublished":"2022-02-11T10:23:57+00:00","dateModified":"2023-11-02T20:43:48+00:00","mainEntityOfPage":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/"},"wordCount":2017,"commentCount":0,"image":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#primaryimage"},"thumbnailUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg","keywords":["dispositifs m\u00e9dicaux"],"articleSection":["audit"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/","url":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/","name":"Audits et rapports sur les dispositifs m\u00e9dicaux - ISO 13485","isPartOf":{"@id":"https:\/\/proqc.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#primaryimage"},"image":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#primaryimage"},"thumbnailUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg","datePublished":"2022-02-11T10:23:57+00:00","dateModified":"2023-11-02T20:43:48+00:00","author":{"@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65"},"description":"L'article explique les types d'audits pour fabricants de dispositifs m\u00e9dicaux, les normes, r\u00e8glements applicables et les rapports d'audit.","breadcrumb":{"@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#primaryimage","url":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg","contentUrl":"https:\/\/proqc.fr\/blog\/wp-content\/uploads\/2022\/02\/Medical-device-manufacturer-audit-ISO-13485-scaled-1.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/proqc.fr\/blog\/comprendre-les-audits-de-dispositifs-medicaux-et-leurs-rapports-daudit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proqc.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Comprendre les audits de dispositifs m\u00e9dicaux et leurs rapports d&rsquo;audit"}]},{"@type":"WebSite","@id":"https:\/\/proqc.fr\/blog\/#website","url":"https:\/\/proqc.fr\/blog\/","name":"Blog de Pro QC","description":"Informez-vous sur les derni\u00e8res nouvelles et les \u00e9volutions du monde du contr\u00f4le qualit\u00e9 gr\u00e2ce au blog de Pro QC International.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proqc.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proqc.fr\/blog\/#\/schema\/person\/f103c8700f64ca2a7c8bb9fe24879a65","name":"deborah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3eb38944d2825c053ac31904d6451d91891f27310ce1d4d0d49368f7dde4f43e?s=96&d=mm&r=g","caption":"deborah"},"url":"https:\/\/proqc.fr\/blog\/author\/deborah\/"}]}},"_links":{"self":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/comments?post=2601"}],"version-history":[{"count":4,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2601\/revisions"}],"predecessor-version":[{"id":2605,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/posts\/2601\/revisions\/2605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/media\/2600"}],"wp:attachment":[{"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/media?parent=2601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/categories?post=2601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proqc.fr\/blog\/wp-json\/wp\/v2\/tags?post=2601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}